{"id":1013,"date":"2012-10-31T01:15:50","date_gmt":"2012-10-31T03:15:50","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=1013"},"modified":"2019-04-29T17:19:53","modified_gmt":"2019-04-29T20:19:53","slug":"jose-serra-vence-fernando-haddad-no-bairro-da-barra-funda","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/jose-serra-vence-fernando-haddad-no-bairro-da-barra-funda\/","title":{"rendered":"Jos\u00e9 Serra vence Fernando Haddad no bairro da Barra Funda"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital.<\/p>\n<p>O Encontra S\u00e3o Paulo realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o do bairro da Barra Funda, que pertence ao col\u00e9gio eleitoral da Bela Vista, o candidato do PSDB foi o mais votado. Veja como ficou a divis\u00e3o:<\/p>\n<p><strong>Jos\u00e9 Serra (PSDB)<\/strong> \u2013 66,96%<\/p>\n<p><strong>Fernando Haddad (PT)<\/strong> \u2013 33,04%<\/p>\n<p>Para conferir como ficou a vota\u00e7\u00e3o em todos os 58 col\u00e9gios eleitorais de S\u00e3o Paulo, acesse o link\u00a0http:\/\/eleicoes.folha.uol.com.br\/2012\/2turno\/mapa-sao_paulo.shtml.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Fernando Haddad (PT) foi eleito neste domingo prefeito da cidade de S\u00e3o Paulo com 3.387.720 votos, equivalente a 55,57% dos votos v\u00e1lidos. J\u00e1 Jos\u00e9 Serra (PSDB) teve a prefer\u00eancia de 2.708.768 paulistanos, terminando a disputa com 44,43% do eleitorado da capital. O Encontra S\u00e3o Paulo realizou um levantamento dos votos em todas as regi\u00f5es da cidade. Na regi\u00e3o do bairro da Barra Funda, que pertence ao col\u00e9gio eleitoral da Bela Vista, o candidato do PSDB foi o mais votado. Veja como ficou a divis\u00e3o: Jos\u00e9 Serra (PSDB) \u2013 66,96% Fernando Haddad (PT) \u2013 33,04% Para conferir como ficou a vota\u00e7\u00e3o <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1013","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1013"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1013\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}