{"id":1109,"date":"2013-01-08T12:02:09","date_gmt":"2013-01-08T14:02:09","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=1109"},"modified":"2019-04-29T17:19:52","modified_gmt":"2019-04-29T20:19:52","slug":"oficina-cultural-da-barra-funda-oferece-programacao-das-atividades-de-ferias","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/oficina-cultural-da-barra-funda-oferece-programacao-das-atividades-de-ferias\/","title":{"rendered":"Oficina Cultural da Barra Funda oferece programa\u00e7\u00e3o das atividades de f\u00e9rias"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Durante janeiro de 2013, as 21 Oficinas Culturais do Estado de S\u00e3o Paulo abrem as inscri\u00e7\u00f5es para a programa\u00e7\u00e3o das atividades de f\u00e9rias \u2013 janeiro a mar\u00e7o \u2013 em todo o estado de S\u00e3o Paulo. Ser\u00e3o oferecidas 145 atividades e 5.232 vagas para oficinas, workshops, debates, palestras.<\/p>\n<p>Um dos destaques da programa\u00e7\u00e3o do interior do Estado \u00e9 a oficina Arte P\u00fablica \u2013 Campinas como cidade centro do Mundo, que acontecer\u00e1 na Oficina Cultural Hilda Hilst, em Campinas. Sob coordena\u00e7\u00e3o de Sylvia Furegatti, a proposta ser\u00e1 criar interven\u00e7\u00f5es art\u00edsticas extramuros, explorando o contexto da arte p\u00fablica e urbana e difundindo variantes formas est\u00e9ticas. A atividade ir\u00e1 propor reflex\u00f5es te\u00f3ricas que resultar\u00e3o efetivamente numa a\u00e7\u00e3o art\u00edstica no centro da cidade de Campinas.<\/p>\n<p>Outro destaque \u00e9 a Oficina de Live Animation, que acontece na Oficina Cultural Grande Otelo, na cidade de Sorocaba. Lucas Luciano coordenar\u00e1 a atividade que \u00e9 a arte de criar um filme, ficcional ou n\u00e3o, em tempo real, captado pela c\u00e2mera na sequ\u00eancia narrativa e utilizando recursos de teatro de anima\u00e7\u00e3o, artes visuais e m\u00fasica. O objetivo da oficina \u00e9 despertar o olhar pr\u00e1tico para as etapas da constru\u00e7\u00e3o de um filme, da montagem do espa\u00e7o para a performance at\u00e9 a explora\u00e7\u00e3o das possibilidades permitidas pelo uso de m\u00faltiplas linguagens.<\/p>\n<p>O destaque da Oficina Cultural Carlos Gomes, em Limeira, ser\u00e1 o workshop O Conceito Art\u00edstico da Instala\u00e7\u00e3o. A atividade ser\u00e1 coordenada por Laura Vinci que ir\u00e1 falar sobre o conceito art\u00edstico de instala\u00e7\u00e3o e o espa\u00e7o contempor\u00e2neo dentro das artes visuais, ampliando o repert\u00f3rio de a\u00e7\u00f5es que envolvem esta linguagem.<\/p>\n<p>Na Capital, um dos destaques da programa\u00e7\u00e3o \u00e9 o workshop de dan\u00e7a Consci\u00eancia do Movimento, que ser\u00e1 ministrado por Angel Vianna, uma das principais figuras da dan\u00e7a contempor\u00e2nea no Brasil, que ensina dan\u00e7a desde 1948. As aulas acontecer\u00e3o na Oficina Cultural Oswald de Andrade, que tamb\u00e9m promover\u00e1 o workshop Jogos Teatrais do Th\u00e9\u00e2tre du Soleil, com Juliana Carneiro da Cunha e Eve Doe Bruce, integrantes da Cia. Th\u00e9\u00e2tre du Soleil.<\/p>\n<p>Outro destaque na Capital ser\u00e1 o workshop sobre Gest\u00e3o Cultural que acontecer\u00e1 na Oficina da Palavra Casa M\u00e1rio de Andrade (Barra Funda). Thiago Ribeiro falar\u00e1 sobre crowdfunding \u2013 modalidade virtual de financiamento coletivo que, por meio da internet, vem ganhando espa\u00e7o no mundo. J\u00e1 a oficina Cultural Alfredo Volpi (Itaquera) botar\u00e1 em movimento o Projeto Expresso Cultural: um \u00f4nibus que levar\u00e1 os participantes a visitas monitoradas em espa\u00e7os de cultura e lazer da regi\u00e3o como o SESC Itaquera, o Parque Ecol\u00f3gico do Tiet\u00ea, o Planet\u00e1rio do Carmo e o SESI A. E. Carvalho. Uma excelente oportunidade para que os participantes conhe\u00e7am a hist\u00f3ria de Itaquera e seu entorno, descobrindo caminhos da cultura local muitas vezes desconhecidos.<\/p>\n<p>Das 21 Oficinas Culturais, seis est\u00e3o instaladas na capital (Bom Retiro, Br\u00e1s, Barra Funda, Itaquera, Cohab Taipas e S\u00e3o Miguel Paulista) e 15 no interior (Ara\u00e7atuba, Araraquara, Bauru, Campinas, Iguape, Limeira, Mar\u00edlia, Presidente Prudente, Ribeir\u00e3o Preto, Santos, S\u00e3o Carlos, S\u00e3o Jo\u00e3o da Boa Vista, S\u00e3o Jos\u00e9 do Rio Preto, S\u00e3o Jos\u00e9 dos Campos e Sorocaba).<\/p>\n<p>As inscri\u00e7\u00f5es s\u00e3o gratuitas e devem ser realizadas em cada unidade das Oficinas Culturais.<\/p>\n<p><strong>Confira o endere\u00e7o da Oficina Cultural na Barra Funda<br \/>\n<\/strong><\/p>\n<p>Oficina da Palavra Casa M\u00e1rio de Andrade<br \/>\nRua Lopes Chaves, 546 &#8211; Barra Funda &#8211; Cep: 01154-010 &#8211; Guia de\u00a0 S\u00e3o Paulo &#8211; SP<br \/>\nTelefone: (11) 3666-5803 \/ 3826-4085 | casamariodeandrade@oficinasculturais.org.br<br \/>\nFuncionamento: Segunda a sexta-feira das 13h \u00e0s 22h (Inscri\u00e7\u00f5es at\u00e9 as 20hs) e s\u00e1bado das 10h \u00e0s 14h<\/p>\n<p><em>Fonte: Oficinas Culturais do Estado<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Durante janeiro de 2013, as 21 Oficinas Culturais do Estado de S\u00e3o Paulo abrem as inscri\u00e7\u00f5es para a programa\u00e7\u00e3o das atividades de f\u00e9rias \u2013 janeiro a mar\u00e7o \u2013 em todo o estado de S\u00e3o Paulo. Ser\u00e3o oferecidas 145 atividades e 5.232 vagas para oficinas, workshops, debates, palestras. Um dos destaques da programa\u00e7\u00e3o do interior do Estado \u00e9 a oficina Arte P\u00fablica \u2013 Campinas como cidade centro do Mundo, que acontecer\u00e1 na Oficina Cultural Hilda Hilst, em Campinas. Sob coordena\u00e7\u00e3o de Sylvia Furegatti, a proposta ser\u00e1 criar interven\u00e7\u00f5es art\u00edsticas extramuros, explorando o contexto da arte p\u00fablica e urbana e difundindo variantes <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1109","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1109"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1109\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}