{"id":1160,"date":"2013-02-21T16:07:30","date_gmt":"2013-02-21T18:07:30","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=1160"},"modified":"2019-04-29T17:19:22","modified_gmt":"2019-04-29T20:19:22","slug":"espetaculo-sem-titulo-estreia-na-barra-funda","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/espetaculo-sem-titulo-estreia-na-barra-funda\/","title":{"rendered":"Espet\u00e1culo Sem T\u00edtulo estreia na Barra Funda"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A core\u00f3grafa, bailarina e diretora da Cia. Fragmento de Dan\u00e7a Vanessa Macedo organiza, entre os dias 21 e 24 de fevereiro de 2013, o evento \u201cInvestiga\u00e7\u00f5es Dramat\u00fargicas\u201d no Kasulo Espa\u00e7o de Cultura e Arte. O projeto, contemplado pelo 12\u00ba edital do programa de Fomento \u00e0 Dan\u00e7a para a Cidade de S\u00e3o Paulo, traz um estudo coreogr\u00e1fico in\u00e9dito de Vanessa, \u201cSEM T\u00cdTULO\u201d, que vai ser interpretado pelos artistas convidados Angela Nolf, Lavinia Bizzotto e Roberto Alencar. Ap\u00f3s as apresenta\u00e7\u00f5es, quatro provocadores (um a cada dia: Nirvana Marinho, Rosa H\u00e9rcules, B\u00e9rgson Queiroz e Silvia Geraldi) far\u00e3o o debate com a plateia.<\/p>\n<p>Vanessa criou uma coreografia de 15 minutos e a entregou para cada um dos artistas convidados, cada um deles\u00a0 se apropriou desse material e comp\u00f4s uma encena\u00e7\u00e3o pr\u00f3pria. A escolha dos elementos que fazem parte do espet\u00e1culo &#8211; trilha sonora, figurino, luz e a pr\u00f3pria din\u00e2mica ou repeti\u00e7\u00e3o de movimento &#8211; ficou a crit\u00e9rio e escolha dos int\u00e9rpretes. A ideia \u00e9 trazer \u00e0 tona a discuss\u00e3o do quanto as escolhas individuais, e o pr\u00f3prio fato de terem trajet\u00f3rias t\u00e3o diferentes entre si, afetam a dramaturgia de uma cria\u00e7\u00e3o em dan\u00e7a com uma partitura j\u00e1 composta, ou seja, reflete sobre a dramaturgia do espet\u00e1culo tendo a coreografia como elemento comum.<\/p>\n<p>\u201cTrata-se de um projeto que tem car\u00e1ter de estudo e a ideia \u00e9 discutir dramaturgia em dan\u00e7a tendo, de um lado, uma coreografia em comum, de outro, artistas int\u00e9rpretes, com trajet\u00f3rias diversas e exclusivamente espec\u00edficas. No que isso vai dar? N\u00e3o sei. \u00c9 isso que queremos &#8211; levantar quest\u00f5es&#8221; explica Vanessa Macedo. O objetivo \u00e9 saber como os elementos c\u00eanicos trabalham o conceito do espet\u00e1culo e se eles podem realmente mudar o \u201ctexto\u201d do corpo, ou seja, as rela\u00e7\u00f5es coreogr\u00e1ficas existentes entre o corpo e o pr\u00f3prio conceito da pe\u00e7a.<\/p>\n<p><strong>Cia. Fragmento de Dan\u00e7a<\/strong><br \/>\nCom dire\u00e7\u00e3o de Vanessa Macedo, a companhia paulista Fragmento de Dan\u00e7a desenvolve pesquisa e cria\u00e7\u00e3o em dan\u00e7a contempor\u00e2nea desde 2002. Na busca de uma dan\u00e7a teatralizada, preocupa-se com a constru\u00e7\u00e3o de uma dramaturgia do corpo e da cena coerente com os temas pesquisados. Suas cria\u00e7\u00f5es s\u00e3o marcadas pela inspira\u00e7\u00e3o em artistas, obras e conte\u00fados, especialmente, confessionais. Discute, a partir da\u00ed, rela\u00e7\u00f5es vividas pelo homem, enquanto ser social, e ser solit\u00e1rio.\u00a0 Envolvida nessas quest\u00f5es, a Cia procura construir um vocabul\u00e1rio de movimento pr\u00f3prio, em busca de uma est\u00e9tica dramat\u00fargica autoral. Entre seus \u00faltimos trabalhos est\u00e3o \u201cCorpos Fr\u00e1geis\u201d (2010), \u201cAnjos Negros\u201d (2010), \u201cEcos\u201d (2011) e \u201cNuvens Insetos\u201d (2012).<\/p>\n<p><strong>Lavinia Bizzotto<\/strong><br \/>\nBailarina profissional de contempor\u00e2neo, foi integrante da Quasar Cia. de Dan\u00e7a por 10 anos, formada no curso profissionalizante do CAL., no rio de Janeiro.\u00a0 Em 2008, a convite do SESC, participou do projeto Solos de Dan\u00e7a do Sesc, o\u00a0 qual resultou no trabalho solo \u201c Na Dobra do Tempo\u201d se apresentando em\u00a0 festivais importantes, como: Festival de Artes\u00a0 C\u00eanicas Goi\u00e2nia em Cena,\u00a0 Panorama Sesi de Dan\u00e7a, I Mostra Carioca de Dan\u00e7a Contempor\u00e2nea, Festival de Inverno de Nova Friburgo e Bienal Internacional do Cear\u00e1. Assina a dire\u00e7\u00e3o de Movimento e Prepara\u00e7\u00e3o Corporal das pe\u00e7as: &#8220;Savana Glacial&#8221;, Dire\u00e7\u00e3o de Renato Carrera, 2010 Sesc De Copacabana, pe\u00e7a esta reconhecida como obra-prima por B\u00e1rbara\u00a0 Heliodora, com destaque para a &#8220;\u00f3tima dire\u00e7\u00e3o de movimento de Lavinia Bizzotto&#8221; e a pe\u00e7a &#8220;O Matador de Santas&#8221;, dire\u00e7\u00e3o Guilherme Leme. Atualmente atua como protagonista do longa-metragem &#8220;Amores Raros&#8221;, dire\u00e7\u00e3o de T\u00e2nia Lamarca, e dan\u00e7a profissionalmente na Cia. de Dan\u00e7a Renato Vieira.<\/p>\n<p><strong>Angela Nolf<\/strong><br \/>\nDepois de formar-se em S\u00e3o Paulo, Angela estudou na Royal Ballet School, entre outras escolas brit\u00e2nicas. Foi bailarina do National Ballet de Israel e ap\u00f3s voltar ao Brasil, em 1983, assumiu a dire\u00e7\u00e3o art\u00edstica do Bal\u00e9 \u00d3pera Paulista. Atuou como bailarina nas companhias Terceira Dan\u00e7a, Druw e elaborou um n\u00facleo de estudos coreogr\u00e1ficos com a bailarina Deborah Furquim. Participa de produ\u00e7\u00f5es independentes, coordena o curso de gradua\u00e7\u00e3o em dan\u00e7a da Unicamp e desenvolve pesquisa sobre o ensino da t\u00e9cnica de dan\u00e7a cl\u00e1ssica para bailarinos contempor\u00e2neos.<br \/>\nRoberto Alencar<\/p>\n<p>\u00c9 ator, bailarino e core\u00f3grafo. Integrou o elenco da Cia Borelli de Dan\u00e7a de 1999 a 2010, sob a dire\u00e7\u00e3o de Sandro Borelli, onde atuou tamb\u00e9m assistente de coreografia. Na Companhia, participou como int\u00e9rprete de mais de uma dezena de espet\u00e1culos. Como bailarino convidado, entre v\u00e1rios outros espet\u00e1culos, integrou o elenco de \u201cUma flor e dois tempos\u201d, em comemora\u00e7\u00e3o aos 20 anos da companhia francesa \u201c\u00c0 fleur de peau\u201d, com dire\u00e7\u00e3o de Denise Namura e Michael Bugdahn, e \u201cUma l\u00e1grima no rosto\u201d, solo desenvolvido com o apoio da Bolsa Rede Stagium, coreografia e dire\u00e7\u00e3o de Ana Teixeira.<\/p>\n<p>Atualmente faz parte do N\u00facleo Expedi\u00e7\u00f5es, grupo de pesquisa em dan\u00e7a \u2013 teatro dirigido por Renata Melo e Vivien Buckup, e tamb\u00e9m concebeu e dirigiu, em parceria com L\u00facia Romano, o espet\u00e1culo \u201cUm porco sentado\u201d, inspirado no fot\u00f3grafo ingl\u00eas John Deakin e no pintor irland\u00eas Francis Bacon. O projeto foi contemplado no 14\u00ba Cultura Inglesa Festival e premiado como o melhor espet\u00e1culo de dan\u00e7a de 2010.<br \/>\nComo ator, j\u00e1 trabalhou em cinema, televis\u00e3o e teatro. Entre outras produ\u00e7\u00f5es, trabalhou em \u201cSalve geral\u201d (cinema), dire\u00e7\u00e3o de Sergio Resende; \u201cCarandiru \u2013 outras hist\u00f3rias\u201d (Rede Globo), miniss\u00e9rie dirigida por Hector Babenco e Marcia Faria; e \u201cMist\u00e9rios gasosos\u201d (teatro), de Oswald de Andrade, dire\u00e7\u00e3o de Jos\u00e9 Celso Martinez Corr\u00eaa.<\/p>\n<p><strong>SERVI\u00c7O NO BAIRRO DA BARRA FUNDA<\/strong><br \/>\n<strong>Quando:<\/strong> de 21 a 24 de fevereiro de 2013 Hor\u00e1rio: quinta a s\u00e1bado, 20h, domingo \u00e0s 19h<br \/>\n<strong>Local:<\/strong> Kasulo Espa\u00e7o de Cultura e Arte<br \/>\n<strong>Endere\u00e7o:<\/strong> Rua Sousa Lima, 300\/Sobreloja, Barra Funda (pr\u00f3ximo ao Teatro S\u00e3o Pedro)<br \/>\n<strong>Informa\u00e7\u00f5es:<\/strong> (11) 3666-7238 \u2013 Lota\u00e7\u00e3o: 40 lugares \u2013 Entrada Franca<br \/>\n<strong>Recomenda\u00e7\u00e3o et\u00e1ria:<\/strong> 14 anos Dura\u00e7\u00e3o total: 45 minutos (15 minutos cada artista, cada coreografia)<br \/>\n<strong>Provocadores ap\u00f3s os espet\u00e1culos:<\/strong> Nirvana Marinho (21\/02), Rosa H\u00e9rcules (22\/02), B\u00e9rgson Queiroz (23\/02) e Silvia Geraldi (24\/02).<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A core\u00f3grafa, bailarina e diretora da Cia. Fragmento de Dan\u00e7a Vanessa Macedo organiza, entre os dias 21 e 24 de fevereiro de 2013, o evento \u201cInvestiga\u00e7\u00f5es Dramat\u00fargicas\u201d no Kasulo Espa\u00e7o de Cultura e Arte. O projeto, contemplado pelo 12\u00ba edital do programa de Fomento \u00e0 Dan\u00e7a para a Cidade de S\u00e3o Paulo, traz um estudo coreogr\u00e1fico in\u00e9dito de Vanessa, \u201cSEM T\u00cdTULO\u201d, que vai ser interpretado pelos artistas convidados Angela Nolf, Lavinia Bizzotto e Roberto Alencar. Ap\u00f3s as apresenta\u00e7\u00f5es, quatro provocadores (um a cada dia: Nirvana Marinho, Rosa H\u00e9rcules, B\u00e9rgson Queiroz e Silvia Geraldi) far\u00e3o o debate com a plateia. Vanessa <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1160","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1160"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1160\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}