{"id":1328,"date":"2013-07-11T12:29:52","date_gmt":"2013-07-11T14:29:52","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=1328"},"modified":"2019-04-29T17:19:20","modified_gmt":"2019-04-29T20:19:20","slug":"picadeiro-diverte-criancas-e-adultos-na-barra-funda","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/picadeiro-diverte-criancas-e-adultos-na-barra-funda\/","title":{"rendered":"Picadeiro diverte crian\u00e7as e adultos na Barra Funda"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Crian\u00e7as olhando para todos os lados, apreensivas com os malabaristas ou dando risadas instantes depois com os palha\u00e7os. Quem quiser ver essas imagens \u00e9 s\u00f3 observar o \u201crespeit\u00e1vel p\u00fablico\u201d dos diversos circos montados em S\u00e3o Paulo, nessas f\u00e9rias de julho. A capital tem v\u00e1rias op\u00e7\u00f5es.<\/p>\n<p>A divers\u00e3o \u00e9 garantida nas diversas arenas montadas em S\u00e3o Paulo, nos circos que atraem uma plateia formada por \u201ccrian\u00e7as\u201d de todas as idades. S\u00e3o shows de malabarismo, pirueta, perna-de-pau, equilibrismo, contorcionismo, trap\u00e9zio, m\u00e1gica e muita palha\u00e7ada.<\/p>\n<p><strong>Saiba mais:<\/strong><\/p>\n<p><strong>Circo dos Sonhos<\/strong><br \/>\n\u201cQuyrey, uma aventura na selva do Circo dos Sonhos\u201d \u00e9 um espet\u00e1culo in\u00e9dito que apresenta a aventura de duas crian\u00e7as transportadas do seu guarda-roupa para a selva Quyrey, que em tupi-guarani significa \u201ccorajoso\u201d.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n<p><strong>Local:<\/strong> Av. Nicolas Boer, 120 (ao lado do Viaduto Pomp\u00e9ia), Barra Funda<br \/>\n<strong>Hor\u00e1rios:<\/strong> s\u00e1bados, domingos e feriados \u00e0s 15h, 17h e 19h30<br \/>\n<strong>Quanto:<\/strong> de R$ 40 a R$ 80. Camarote R$ 300 (4 lugares). Meia-entrada para crian\u00e7as de 2 a 12 anos, estudantes e idosos. Vendas: ingresso.com, televendas no 4003-2330 ou diretamente na bilheteria do circo.\u00a0 Hor\u00e1rio da bilheteria: de segunda a sexta-feira das 10h \u00e0s 12h e das 13h \u00e0s 18h. S\u00e1bados, domingos e feriados das 10h \u00e0s 19h30. Estacionamento: R$ 15,00<br \/>\n<strong>Classifica\u00e7\u00e3o:<\/strong> livre<br \/>\n<strong>Informa\u00e7\u00f5es:<\/strong> 2067-0001 ou 2076-0787<\/p>\n<p><em>Fonte: G1<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Crian\u00e7as olhando para todos os lados, apreensivas com os malabaristas ou dando risadas instantes depois com os palha\u00e7os. Quem quiser ver essas imagens \u00e9 s\u00f3 observar o \u201crespeit\u00e1vel p\u00fablico\u201d dos diversos circos montados em S\u00e3o Paulo, nessas f\u00e9rias de julho. A capital tem v\u00e1rias op\u00e7\u00f5es. A divers\u00e3o \u00e9 garantida nas diversas arenas montadas em S\u00e3o Paulo, nos circos que atraem uma plateia formada por \u201ccrian\u00e7as\u201d de todas as idades. S\u00e3o shows de malabarismo, pirueta, perna-de-pau, equilibrismo, contorcionismo, trap\u00e9zio, m\u00e1gica e muita palha\u00e7ada. Saiba mais: Circo dos Sonhos \u201cQuyrey, uma aventura na selva do Circo dos Sonhos\u201d \u00e9 um espet\u00e1culo in\u00e9dito <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1328","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1328"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1328\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}