{"id":173,"date":"2011-01-31T21:44:12","date_gmt":"2011-01-31T23:44:12","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=173"},"modified":"2019-04-29T17:21:25","modified_gmt":"2019-04-29T20:21:25","slug":"ex-destinys-child-faz-shows-no-brasil-em-marco-na-barra-funda","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/ex-destinys-child-faz-shows-no-brasil-em-marco-na-barra-funda\/","title":{"rendered":"Ex-Destiny&#8217;s Child faz shows no Brasil em mar\u00e7o na Barra Funda"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A cantora norte-americana Kelly Rowland far\u00e1 dois shows no Brasil em  mar\u00e7o. A ex-integrante do grupo vocal Destiny&#8217;s Child, do qual Beyonc\u00e9  tamb\u00e9m fez parte, tem apresenta\u00e7\u00f5es marcardas em S\u00e3o Paulo, no Bairro da Barra Funda, no dia 5; e  em Florian\u00f3polis, no dia 6.<\/p>\n<p>Dona da 2\u00ba m\u00fasica mais executada no mundo em 2010, &#8220;When love takes  over&#8221;, Kelly deu in\u00edcio \u00e0 sua carreira solo em 2002, quando gravou a  can\u00e7\u00e3o &#8220;Dilemma&#8221; em parceria com o rapper Nelly. No ano seguinte,  lan\u00e7aria seu primeiro disco solo, &#8220;Simply deep&#8221;. Em junho de 2007, saiu  &#8220;Ms. Kelly&#8221;, disco que contou a colabora\u00e7\u00e3o, entre outros do rapper  Snoop Dogg.<\/p>\n<p>Junto do Destiny&#8217;s Child, vendeu mais de 50 milh\u00f5es de CDs pelo mundo,  emplacou 4 hits em primeiro lugar na tradicional parada da revista  &#8220;Billboard&#8221; e foi homenageada com uma estrela na Cal\u00e7ada da Fama de  Holywood em mar\u00e7o de 2006.<\/p>\n<p><strong>Kelly Rowland em S\u00e3o Paulo<\/strong><br \/>\n<strong>Onde:<\/strong> Local Flexx, Avenida Marqu\u00eas de S\u00e3o Vicente, 1.767 &#8211; guia do bairro da Barra Funda<br \/>\n<strong>Quando:<\/strong> s\u00e1bado de carnaval (5 de mar\u00e7o)<br \/>\n<strong>Hor\u00e1rio:<\/strong> 22h<br \/>\n<strong>Ingressos:<\/strong> R$ 60; \u00e0 venda na internet pelo site blueticket.com.br ou nos postos autorizados<br \/>\n<strong>Informa\u00e7\u00f5es:<\/strong> (11) 3612-4402<\/p>\n<p><strong>Kelly Rowland em Florian\u00f3polis<\/strong><br \/>\n<strong>Onde:<\/strong> Lagoa Iate Club (Lic), Rua Hyp\u00f3lito V. Pereira, 620 &#8211; Lagoa da Concei\u00e7\u00e3o<br \/>\n<strong>Quando:<\/strong> domingo de carnaval (6 de mar\u00e7o)<br \/>\n<strong>Hor\u00e1rio:<\/strong> 23h<br \/>\n<strong>Ingressos:<\/strong> R$ 60; \u00e0 venda na internet pelo site blueticket.com.br ou nos postos autorizados<\/p>\n<p><em>Fonte: G1<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A cantora norte-americana Kelly Rowland far\u00e1 dois shows no Brasil em mar\u00e7o. A ex-integrante do grupo vocal Destiny&#8217;s Child, do qual Beyonc\u00e9 tamb\u00e9m fez parte, tem apresenta\u00e7\u00f5es marcardas em S\u00e3o Paulo, no Bairro da Barra Funda, no dia 5; e em Florian\u00f3polis, no dia 6. Dona da 2\u00ba m\u00fasica mais executada no mundo em 2010, &#8220;When love takes over&#8221;, Kelly deu in\u00edcio \u00e0 sua carreira solo em 2002, quando gravou a can\u00e7\u00e3o &#8220;Dilemma&#8221; em parceria com o rapper Nelly. No ano seguinte, lan\u00e7aria seu primeiro disco solo, &#8220;Simply deep&#8221;. Em junho de 2007, saiu &#8220;Ms. Kelly&#8221;, disco que contou a <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-173","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=173"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/173\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}