{"id":2791,"date":"2013-09-20T00:22:23","date_gmt":"2013-09-20T02:22:23","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=2791"},"modified":"2019-04-29T17:19:19","modified_gmt":"2019-04-29T20:19:19","slug":"barra-funda-recebera-virada-esportiva-2013","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/barra-funda-recebera-virada-esportiva-2013\/","title":{"rendered":"Barra Funda receber\u00e1 Virada Esportiva 2013"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Nos dias 21 e 22 de setembro acontece a s\u00e9tima Virada Esportiva. A Secretaria de Esportes, Lazer e Recrea\u00e7\u00e3o promover\u00e1 mais de duas mil atividades em cerca de 200 locais espalhados por toda a cidade. Centros esportivos municipais, parques, CEU&#8217;s e outros cart\u00f5es-postais da cidade como o Vale do Anhangaba\u00fa e o Memorial da Am\u00e9rica Latina ser\u00e3o ocupados desde as 8h da manh\u00e3 do s\u00e1bado at\u00e9 \u00e0s 18h do domingo. Com a miss\u00e3o de trazer um final de semana ininterrupto de atividade f\u00edsica, esporte, lazer e recrea\u00e7\u00e3o, em uma maratona de 34 horas planejada com dois objetivos: descentraliza\u00e7\u00e3o e participa\u00e7\u00e3o. Mais de 95% dos eventos oferecidos na programa\u00e7\u00e3o ser\u00e3o participativos, isto \u00e9, atividades em que o p\u00fablico pode experimentar na pr\u00e1tica algum tipo de atividade esportiva, lazer ou recrea\u00e7\u00e3o. A descentraliza\u00e7\u00e3o tamb\u00e9m \u00e9 regra. O \u201cmapa\u201d da programa\u00e7\u00e3o espalha-se por todas as 31 subprefeituras, com op\u00e7\u00f5es em todas as regi\u00f5es da capital. Segundo pesquisa Ibope realizada durante a sexta edi\u00e7\u00e3o do evento, em junho de 2012, 99% dos paulistanos participantes aprovam a realiza\u00e7\u00e3o da Virada Esportiva.<\/p>\n<p>\u201cA grande for\u00e7a da Virada Esportiva 2013 \u00e9 esta rede de eventos essencialmente participativos. Foi preciso muito esfor\u00e7o para que consegu\u00edssemos oferecer op\u00e7\u00f5es em que as pessoas possam realmente tornar-se participantes e n\u00e3o apenas espectadores da Virada\u201d, afirma Celso Jatene, Secret\u00e1rio de Esportes do munic\u00edpio.<\/p>\n<p>Neste ano, a Virada Esportiva coincide com duas datas importantes para a Cidade de S\u00e3o Paulo: s\u00e1bado, 21 de setembro, \u00e9 o Dia Nacional de Luta pelos Direitos da Pessoa com Defici\u00eancia, o domingo, 22, a celebra\u00e7\u00e3o do Dia Mundial Sem Carro (22\/9). A utiliza\u00e7\u00e3o do transporte p\u00fablico e de outros meios como a bicicleta ser\u00e1 incentivada na Virada. Pessoas com defici\u00eancia f\u00edsica ou intelectual tamb\u00e9m ter\u00e3o diversas atividades durante todo o final de semana esportivo.<\/p>\n<p>E a pr\u00e1tica esportiva em hor\u00e1rios inusitados, durante a madrugada, n\u00e3o ser\u00e1 oferecida apenas nos dias 21 e 22 de setembro. Pensando em continuar oferecendo a oportunidade da pr\u00e1tica noturna de esportes, a Prefeitura passa a executar o programa &#8216;Revirando A Virada&#8217;, exatamente uma semana ap\u00f3s a realiza\u00e7\u00e3o da s\u00e9tima edi\u00e7\u00e3o do evento. A partir do dia 28 de setembro, onze centros esportivos e o Parque Ibirapuera v\u00e3o passar a funcionar por 24 horas nos finais de semana. At\u00e9 2016, 32 equipamentos esportivos v\u00e3o fazer parte do \u201cRevirando a Virada\u201d.<\/p>\n<p>\u201cEsta iniciativa \u00e9 uma maneira de fomentar um servi\u00e7o de esporte continuado \u00e0 popula\u00e7\u00e3o por todo o ano, mantendo aceso o esp\u00edrito da Virada.\u201d, Celso Jatene, Secret\u00e1rio Municipal de Esportes, Lazer e Recrea\u00e7\u00e3o. \u201cEsta \u00e9 uma das cinco principais metas da Secretaria de Esportes no per\u00edodo 2013-2016\u201d, complementa Jatene.<\/p>\n<p><strong>N\u00fameros<br \/>\n<\/strong><br \/>\nA Virada Esportiva 2013 contar\u00e1 com a participa\u00e7\u00e3o de 45 centros esportivos municipais de administra\u00e7\u00e3o direta, 45 Centros Educacionais Unificados (CEUs), 12 unidades do SESC, 10 parques, al\u00e9m de 90 pra\u00e7as e CDC\u2019s (Clubes da Comunidade). Nesta s\u00e9tima edi\u00e7\u00e3o, ser\u00e3o oferecidas mais de duas mil atividades espalhadas em 200 pontos diferentes. Cerca de 400 volunt\u00e1rios v\u00e3o atuar durante a realiza\u00e7\u00e3o do evento.<\/p>\n<p><strong>Servi\u00e7o:<\/strong><\/p>\n<p>Local: CE Raul Tabajara<br \/>\nEndere\u00e7o: Rua Anhanguera, 484 &#8211; Barra Funda<br \/>\nInforma\u00e7\u00f5es: 3392-5592<br \/>\nModalidade: Diversas<br \/>\nQuando: 21\/09 e 22\/09<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Nos dias 21 e 22 de setembro acontece a s\u00e9tima Virada Esportiva. A Secretaria de Esportes, Lazer e Recrea\u00e7\u00e3o promover\u00e1 mais de duas mil atividades em cerca de 200 locais espalhados por toda a cidade. Centros esportivos municipais, parques, CEU&#8217;s e outros cart\u00f5es-postais da cidade como o Vale do Anhangaba\u00fa e o Memorial da Am\u00e9rica Latina ser\u00e3o ocupados desde as 8h da manh\u00e3 do s\u00e1bado at\u00e9 \u00e0s 18h do domingo. Com a miss\u00e3o de trazer um final de semana ininterrupto de atividade f\u00edsica, esporte, lazer e recrea\u00e7\u00e3o, em uma maratona de 34 horas planejada com dois objetivos: descentraliza\u00e7\u00e3o e participa\u00e7\u00e3o. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2791","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=2791"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2791\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=2791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=2791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=2791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}