{"id":2822,"date":"2013-11-15T00:19:29","date_gmt":"2013-11-15T02:19:29","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=2822"},"modified":"2019-04-29T17:19:19","modified_gmt":"2019-04-29T20:19:19","slug":"barra-funda-casa-das-caldeiras-realiza-festival-caldeirao-do-negao","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/barra-funda-casa-das-caldeiras-realiza-festival-caldeirao-do-negao\/","title":{"rendered":"Barra Funda: Casa das Caldeiras realiza Festival Caldeir\u00e3o do Neg\u00e3o"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A Casa das Caldeiras recebe no domingo, 17, a segunda edi\u00e7\u00e3o do \u201cCaldeir\u00e3o do Neg\u00e3o\u201d, dentro das comemora\u00e7\u00f5es da Semana da Consci\u00eancia Negra.<\/p>\n<p>Entre 15h e 20h, o p\u00fablico pode conferir diversas manifesta\u00e7\u00f5es culturais como dan\u00e7a afro, break, dan\u00e7a de sal\u00e3o, al\u00e9m performances de sapateado, circo e poesia. A entrada \u00e9 gratuita.<\/p>\n<p>Diferentes linguagens art\u00edsticas se manifestam quase que simultaneamente. Poesia, m\u00fasica, dan\u00e7a e interven\u00e7\u00f5es art\u00edsticas apresentam a diversidade proporcionada pela cultura negra.<\/p>\n<p>O evento conta com a apresenta\u00e7\u00e3o da jornalista Chris Gomes e traz expositores como Resisto, Xongani, Nega Fulo, Feira Preta e Negra Pan Fashion. As especiarias gastron\u00f4micas s\u00e3o preparadas por Pakuera, presidente do Samba da Vela. Para completar, o Samba Delas fecha a programa\u00e7\u00e3o com muita m\u00fasica.<\/p>\n<p><strong>Servi\u00e7o<\/strong><br \/>\nO que: Caldeir\u00e3o do Neg\u00e3o<br \/>\nQuando: Dom 17\/11 das 15:00 \u00e0s 20:00<br \/>\nQuanto: Gratuito<br \/>\nOnde: Casa das Caldeiras<br \/>\nEndere\u00e7o: Avenida Francisco Matarazzo, 2000 &#8211; Barra Funda<br \/>\nInforma\u00e7\u00f5es: (11) 3873-6696<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Casa das Caldeiras recebe no domingo, 17, a segunda edi\u00e7\u00e3o do \u201cCaldeir\u00e3o do Neg\u00e3o\u201d, dentro das comemora\u00e7\u00f5es da Semana da Consci\u00eancia Negra. Entre 15h e 20h, o p\u00fablico pode conferir diversas manifesta\u00e7\u00f5es culturais como dan\u00e7a afro, break, dan\u00e7a de sal\u00e3o, al\u00e9m performances de sapateado, circo e poesia. A entrada \u00e9 gratuita. Diferentes linguagens art\u00edsticas se manifestam quase que simultaneamente. Poesia, m\u00fasica, dan\u00e7a e interven\u00e7\u00f5es art\u00edsticas apresentam a diversidade proporcionada pela cultura negra. O evento conta com a apresenta\u00e7\u00e3o da jornalista Chris Gomes e traz expositores como Resisto, Xongani, Nega Fulo, Feira Preta e Negra Pan Fashion. As especiarias gastron\u00f4micas <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2822","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=2822"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/2822\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=2822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=2822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=2822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}