{"id":349,"date":"2011-05-24T14:53:37","date_gmt":"2011-05-24T16:53:37","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=349"},"modified":"2019-04-29T17:21:03","modified_gmt":"2019-04-29T20:21:03","slug":"vai-malhar-amanha-opcoes-na-barra-funda","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/vai-malhar-amanha-opcoes-na-barra-funda\/","title":{"rendered":"Vai malhar amanh\u00e3? Op\u00e7\u00f5es na Barra Funda"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Quem fizer qualquer atividade f\u00edsica amanh\u00e3 em S\u00e3o Paulo &#8211; de aula de  dan\u00e7a na academia at\u00e9 corrida no parque &#8211; poder\u00e1 ajudar a cidade a  ganhar a competi\u00e7\u00e3o do Dia do Desafio, que ocorre no mundo inteiro,  sempre na \u00faltima quarta-feira de maio. Neste ano, a capital paulista  compete com Durango, no M\u00e9xico, e o objetivo \u00e9 reunir o maior n\u00famero de  pessoas fazendo exerc\u00edcio em um \u00fanico dia em cada cidade.<\/p>\n<p>Para participar, basta ligar para 0800-11-8220 e informar o tipo de  esporte ou atividade que voc\u00ea fez. Em S\u00e3o Paulo, as 12 unidades do Sesc  ter\u00e3o aulas que v\u00e3o de ioi\u00f4 e atividades circenses a esgrima e artes  marciais. Empresas e escolas das redes estadual e municipal tamb\u00e9m v\u00e3o  ter programa\u00e7\u00e3o.<\/p>\n<p>V\u00e1rios locais p\u00fablicos na cidade promover\u00e3o exerc\u00edcios coletivos. Na  Esta\u00e7\u00e3o Luz, por exemplo, participantes podem fazer aula de dan\u00e7a  gratuita \u00e0s 12h.<\/p>\n<p>O ex-jogador e t\u00e9cnico de futebol Vampeta vai liderar uma s\u00e9rie de  atividades nas Esta\u00e7\u00f5es Barra Funda (\u00e0s 6h30 e 7h30), Marechal Deodoro  (8h30) e no Sesc Pompeia (9h30). E o ex-jogador de v\u00f4lei Tande tamb\u00e9m  vai dar uma de t\u00e9cnico na Barra Funda \u00e0s 16h30 e \u00e0s 17h, no Shopping  West Plaza \u00e0s 18h e no Sesc Pompeia \u00e0s 19h.<\/p>\n<p><strong>Competi\u00e7\u00e3o.<\/strong> \u00c9 o 16.\u00ba ano que S\u00e3o Paulo participa do  desafio, que surgiu no Canad\u00e1 em 1983. As cidades americanas sempre  competem entre si e a regra \u00e9 a mesma nos outros continentes. No ano  passado, o &#8220;oponente&#8221; de S\u00e3o Paulo foi Santa Cruz de La Sierra, na  Bol\u00edvia, que perdeu o jogo: 10% da popula\u00e7\u00e3o se engajou fisicamente no  dia. Em S\u00e3o Paulo, esse n\u00famero foi de 25%, o que corresponde a mais de  2,6 milh\u00f5es de paulistanos suando a camisa.<\/p>\n<p>\u00c9 uma quantidade expressiva, segundo a gerente de Desenvolvimento  F\u00edsico-Esportivo do Sesc S\u00e3o Paulo, Maria Luiza Souza Dias. &#8220;A gente  percebe que esse evento deixa um legado para o futuro. V\u00e1rios programas  de atividade em escolas, empresas e outras entidades surgiram a partir  do Dia do Desafio.&#8221;<\/p>\n<p>A competi\u00e7\u00e3o entre as cidades \u00e9 amig\u00e1vel e n\u00e3o existe pr\u00eamio para a  mais ativa. O Sesc trabalha neste ano com uma meta ambiciosa: contar com  a ades\u00e3o de 27% dos paulistanos. &#8220;O importante n\u00e3o \u00e9 perder ou ganhar.  Nossa expectativa \u00e9 diminuir o sedentarismo no mundo e motivar as  pessoas por meio do resultado em cada cidade&#8221;, conta Maria Luiza.<\/p>\n<p>O registro de atividades \u00e9 feito por um coordenador em cada uma das  institui\u00e7\u00f5es participantes, al\u00e9m da contabiliza\u00e7\u00e3o das liga\u00e7\u00f5es para o  0800.<\/p>\n<p><strong>PROGRAMA\u00c7\u00c3O<br \/>\n<\/strong><br \/>\n<em>Esta\u00e7\u00f5es<br \/>\n<\/em>Bairro Barra Funda, Tiet\u00ea, Marechal Deodoro e Santa Cec\u00edlia ter\u00e3o atividades<\/p>\n<p><em>Sescs<br \/>\n<\/em>As 12 unidades da capital ter\u00e3o atividades gratuitas, como aulas de circo no Sesc Consola\u00e7\u00e3o<\/p>\n<p><em>Parques<br \/>\n<\/em>Parque do Ibirapuera, <a href=\"http:\/\/www.encontrabarrafunda.com.br\/barra-funda\/parque-da-agua-branca-na-barra-funda.shtml\" target=\"_blank\">Parque da \u00c1gua Branca<\/a>, Parque Independ\u00eancia e Buenos Aires ter\u00e3o caminhadas e alongamento<\/p>\n<p><em>Shoppings<br \/>\n<\/em>A\u00e7\u00f5es no Tatuap\u00e9 e West Plaza<\/p>\n<p><em>Fonte: O Estado de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Quem fizer qualquer atividade f\u00edsica amanh\u00e3 em S\u00e3o Paulo &#8211; de aula de dan\u00e7a na academia at\u00e9 corrida no parque &#8211; poder\u00e1 ajudar a cidade a ganhar a competi\u00e7\u00e3o do Dia do Desafio, que ocorre no mundo inteiro, sempre na \u00faltima quarta-feira de maio. Neste ano, a capital paulista compete com Durango, no M\u00e9xico, e o objetivo \u00e9 reunir o maior n\u00famero de pessoas fazendo exerc\u00edcio em um \u00fanico dia em cada cidade. Para participar, basta ligar para 0800-11-8220 e informar o tipo de esporte ou atividade que voc\u00ea fez. Em S\u00e3o Paulo, as 12 unidades do Sesc ter\u00e3o aulas <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-349","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=349"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/349\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}