{"id":3555,"date":"2026-03-21T08:15:03","date_gmt":"2026-03-21T11:15:03","guid":{"rendered":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/metro-de-sao-paulo-funcionara-24h-durante-o-lollapalooza\/"},"modified":"2026-03-21T08:15:03","modified_gmt":"2026-03-21T11:15:03","slug":"metro-de-sao-paulo-funcionara-24h-durante-o-lollapalooza","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/metro-de-sao-paulo-funcionara-24h-durante-o-lollapalooza\/","title":{"rendered":"Metr\u00f4 de S\u00e3o Paulo funcionar\u00e1 24h durante o Lollapalooza"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<h2>Funcionamento do Metr\u00f4 Durante o Lollapalooza<\/h2>\n<p>Em raz\u00e3o da realiza\u00e7\u00e3o do Festival Lollapalooza, o Metr\u00f4 de S\u00e3o Paulo traz uma opera\u00e7\u00e3o especial que se estende durante os tr\u00eas dias do evento. O sistema funcionar\u00e1 sem interrup\u00e7\u00f5es, proporcionando acesso cont\u00ednuo ao p\u00fablico que deseja participar do festival, garantindo assim maior comodidade e seguran\u00e7a para quem se desloca nas madrugadas.<\/p>\n<h2>Hor\u00e1rios Especiais para o Festival<\/h2>\n<p>Durante o Lollapalooza, as esta\u00e7\u00f5es do Metr\u00f4 passaram a oferecer hor\u00e1rios especiais. Na noite de sexta-feira (20) para s\u00e1bado (21), as esta\u00e7\u00f5es estar\u00e3o abertas exclusivamente para desembarque, permitindo que os festivaleiros retornem para casa ap\u00f3s os shows. O mesmo esquema se repetir\u00e1 na madrugada de domingo (22) para segunda-feira (23), onde novamente haver\u00e1 somente desembarque. No entanto, no s\u00e1bado (21) para domingo (22), a opera\u00e7\u00e3o 24 horas ser\u00e1 ativada, permitindo tanto o embarque quanto o desembarque durante toda a madrugada nas linhas 1-Azul, 2-Verde, 3-Vermelha e 15-Prata.<\/p>\n<h2>Linhas Atendidas na Opera\u00e7\u00e3o 24h<\/h2>\n<p>A opera\u00e7\u00e3o 24 horas abranger\u00e1 as seguintes linhas do Metr\u00f4 de S\u00e3o Paulo:<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-content\/uploads\/2026\/03\/metro-de-sao-paulo-funcionara-24h-durante-o-lollapalooza.webp\" alt=\"funcionamento do metr\u00f4 de S\u00e3o Paulo\" loading=\"lazy\" \/><\/p>\n<ul>\n<li><strong>Linha 1-Azul:<\/strong> Conecta diversas regi\u00f5es centrais.<\/li>\n<li><strong>Linha 2-Verde:<\/strong> Facilita a liga\u00e7\u00e3o entre a Zona Sul e o centro.<\/li>\n<li><strong>Linha 3-Vermelha:<\/strong> Interliga importantes regi\u00f5es da cidade.<\/li>\n<li><strong>Linha 15-Prata:<\/strong> Linha moderna que tamb\u00e9m estar\u00e1 dispon\u00edvel.<\/li>\n<\/ul>\n<p>Este extenso hor\u00e1rio de funcionamento busca oferecer maior flexibilidade aos usu\u00e1rios, especialmente considerando o grande volume de pessoas que devem frequentar o evento.<\/p>\n<h2>Transfer\u00eancias Dispon\u00edveis no Metr\u00f4<\/h2>\n<p>As transfer\u00eancias entre linhas do Metr\u00f4 s\u00e3o essenciais para otimizar o deslocamento dos passageiros durante o festival. As seguintes esta\u00e7\u00f5es estar\u00e3o operando normalmente durante o evento:<\/p>\n<ul>\n<li><strong>Esta\u00e7\u00e3o Luz<\/li>\n<\/ul>\n<li><strong>Corinthians-Itaquera<\/strong><\/li>\n<li><strong>Tatuap\u00e9<\/strong><\/li>\n<li><strong>Br\u00e1s<\/strong><\/li>\n<li><strong>Palmeiras-Barra Funda<\/strong><\/li>\n<li><strong>Tamanduate\u00ed<\/strong><\/li>\n<li><strong>Rep\u00fablica<\/strong><\/li>\n<li><strong>Consola\u00e7\u00e3o<\/strong><\/li>\n<li><strong>Santa Cruz<\/strong><\/li>\n<li><strong>Ch\u00e1cara Klabin<\/strong><\/li>\n<\/ul>\n<p>Esta\u00e7\u00f5es estrat\u00e9gicas como essas garantem que os passageiros possam se mover com efici\u00eancia e rapidez, permitindo a integra\u00e7\u00e3o entre as diferentes linhas e facilitando o acesso ao festival.<\/p>\n<h2>Trem Expresso Lollapalooza<\/h2>\n<p>Outra op\u00e7\u00e3o muito pr\u00e1tica para os visitantes \u00e9 o Trem Expresso Lollapalooza, que estar\u00e1 dispon\u00edvel na Linha 9-Esmeralda. Este servi\u00e7o proporciona uma maneira r\u00e1pida e eficiente de chegar ao local do evento. O embarque ser\u00e1 feito em plataformas exclusivas na esta\u00e7\u00e3o Pinheiros, com paradas limitadas para assegurar que os usu\u00e1rios cheguem rapidamente \u00e0 esta\u00e7\u00e3o Cidade Dutra, que conta com acesso direto aos port\u00f5es do Lollapalooza, evitando paradas em esta\u00e7\u00f5es intermedi\u00e1rias.<\/p>\n<h2>Refor\u00e7o de Seguran\u00e7a nas Esta\u00e7\u00f5es<\/h2>\n<p>Para garantir ainda mais a seguran\u00e7a dos usu\u00e1rios durante o festival, toda a equipe operacional e de seguran\u00e7a estar\u00e1 refor\u00e7ada nas esta\u00e7\u00f5es. Agentes de Atendimento e Seguran\u00e7a estar\u00e3o posicionados em plataformas e trens, prontos para auxiliar e orientar os passageiros em qualquer situa\u00e7\u00e3o, al\u00e9m de monitorar o fluxo de pessoas.<\/p>\n<h2>Dicas de Deslocamento Durante o Evento<\/h2>\n<p>Algumas dicas podem ajudar os usu\u00e1rios a se deslocarem com mais tranquilidade durante o Lollapalooza:<\/p>\n<ul>\n<li><strong>Planeje sua viagem:<\/strong> Verifique os hor\u00e1rios das linhas e tente chegar cedo para evitar aglomera\u00e7\u00f5es.<\/li>\n<li><strong>Use o aplicativo do Metr\u00f4:<\/strong> Acompanhe em tempo real a disponibilidade das linhas e o status do servi\u00e7o.<\/li>\n<li><strong>Mantenha-se atento aos avisos:<\/strong> Fique atento \u00e0s comunica\u00e7\u00f5es visuais e sonoras nas esta\u00e7\u00f5es, que informar\u00e3o sobre a opera\u00e7\u00e3o especial.<\/li>\n<\/ul>\n<h2>Integra\u00e7\u00e3o com Outras Linhas de Trem<\/h2>\n<p>O Metr\u00f4 de S\u00e3o Paulo n\u00e3o estar\u00e1 sozinho em oferecer op\u00e7\u00f5es de transporte durante o Lollapalooza. Os trens da Companhia Paulista de Trens Metropolitanos (CPTM) tamb\u00e9m ter\u00e3o opera\u00e7\u00e3o cont\u00ednua. As linhas 10-Turquesa, 11-Coral, 12-Safira e 13-Jade estar\u00e3o \u00e0 disposi\u00e7\u00e3o, com abertura das esta\u00e7\u00f5es para embarque entre 4h e 00h. O desembarque, por outro lado, estar\u00e1 dispon\u00edvel em qualquer hor\u00e1rio.<\/p>\n<h2>Esta\u00e7\u00f5es com Opera\u00e7\u00e3o Especial<\/h2>\n<p>Al\u00e9m da esta\u00e7\u00e3o Palmeiras-Barra Funda, que funciona como um dos principais pontos de acesso, suas demais esta\u00e7\u00f5es na Linha 7-Rubi estar\u00e3o abertas apenas para desembarque durante as madrugadas do evento. \u00c9 fundamental que os passageiros se informem sobre quais esta\u00e7\u00f5es estar\u00e3o dispon\u00edveis para embarque em cada dia do festival.<\/p>\n<h2>Informa\u00e7\u00f5es sobre Passagens e Pre\u00e7os<\/h2>\n<p>O acesso ao Trem Expresso Lollapalooza ser\u00e1 feito mediante a aquisi\u00e7\u00e3o de um bilhete, que pode ser comprado nas esta\u00e7\u00f5es integralmente ou atrav\u00e9s do site oficial de venda. A passagem de ida e volta custa R$ 35,00, oferecendo um \u00f4nibus de ida e volta at\u00e9 o evento, proporcionando uma experi\u00eancia pr\u00e1tica e acess\u00edvel.<\/p>\n<h2>Hor\u00e1rios do Expresso Lollapalooza<\/h2>\n<p>Os hor\u00e1rios do Trem Expresso s\u00e3o organizados para facilitar os deslocamentos dos usu\u00e1rios:<\/p>\n<h3>Sexta-feira \u2013 20 de mar\u00e7o<\/h3>\n<ul>\n<li>Ida (Esta\u00e7\u00e3o Pinheiros): 11h, 12h, 13h, 14h, 15h, 15h30<\/li>\n<li>Volta (Esta\u00e7\u00e3o Aut\u00f3dromo): 23h, 23h30, 0h, 0h30, 1h, 1h30, 2h, 2h30<\/li>\n<\/ul>\n<h3>S\u00e1bado \u2013 21 de mar\u00e7o<\/h3>\n<ul>\n<li>Ida (Esta\u00e7\u00e3o Pinheiros): 11h, 11h30, 12h, 12h30, 13h, 13h30, 14h, 14h30, 15h, 15h30, 16h<\/li>\n<li>Volta (Esta\u00e7\u00e3o Aut\u00f3dromo): 23h, 23h30, 0h, 0h30, 1h, 1h30, 2h, 2h30<\/li>\n<\/ul>\n<h3>Domingo \u2013 22 de mar\u00e7o<\/h3>\n<ul>\n<li>Ida (Esta\u00e7\u00e3o Pinheiros): 11h, 11h30, 12h, 12h30, 13h, 13h30, 14h, 14h30, 15h, 15h30, 16h<\/li>\n<li>Volta (Esta\u00e7\u00e3o Aut\u00f3dromo): 23h, 23h30, 0h, 0h30, 1h, 1h30, 2h, 2h30<\/li>\n<\/ul>\n<p>Esse esquema de hor\u00e1rios e a opera\u00e7\u00e3o cont\u00ednua do Metr\u00f4 e da CPTM durante o Lollapalooza asseguram que todos os visitantes tenham acesso f\u00e1cil e r\u00e1pido ao evento, al\u00e9m de garantir a seguran\u00e7a e o conforto necess\u00e1rios para uma experi\u00eancia agrad\u00e1vel.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Metr\u00f4 de S\u00e3o Paulo funcionar\u00e1 24 horas durante o Lollapalooza, garantindo transporte para todos.<\/p>\n","protected":false},"author":1,"featured_media":3554,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-na-barra-funda","has_thumb"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/3555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=3555"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/3555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media\/3554"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=3555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=3555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=3555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}