{"id":393,"date":"2011-06-15T05:23:28","date_gmt":"2011-06-15T07:23:28","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=393"},"modified":"2019-04-29T17:21:03","modified_gmt":"2019-04-29T20:21:03","slug":"cet-nao-avalia-lancamentos-sem-garagem-mas-urbanista-preve-impacto-na-regiao-da-barra-funda","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/cet-nao-avalia-lancamentos-sem-garagem-mas-urbanista-preve-impacto-na-regiao-da-barra-funda\/","title":{"rendered":"CET n\u00e3o avalia lan\u00e7amentos sem garagem, mas urbanista prev\u00ea impacto na regi\u00e3o da Barra Funda"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A Companhia de Engenharia de Tr\u00e1fego de S\u00e3o Paulo (CET) n\u00e3o realizou   an\u00e1lise de impacto vi\u00e1rio em nenhum dos empreendimentos sem vagas   lan\u00e7ados em 2010.<\/p>\n<p>A empresa cumpre a lei 10.506\/88, que determina  estudos apenas para  Polos Geradores Tr\u00e1fego. Para que isso ocorra, uma  edifica\u00e7\u00e3o  residencial deve ter pelo menos 500 vagas. Apesar da previs\u00e3o  legal,  especialistas preveem transtornos para a circula\u00e7\u00e3o em algumas  regi\u00f5es.<\/p>\n<p>&#8220;Um tipo de impacto \u00e9 que o espa\u00e7o p\u00fablico seja tomado por ve\u00edculos   particulares&#8221;, diz Luiz Guilherme Castro, professor do Mackenzie   especializado em zoneamento urbano. O empreendimento Premmio Vila Nova,   localizado na zona norte de S\u00e3o Paulo, tem, sozinho, 41 unidades sem   vaga.<\/p>\n<p>A assistente de ger\u00eancia Juliana Cunha, dona de um apartamento no   condom\u00ednio Barra Funda Park, pretende deixar seu autom\u00f3vel nas ruas   quando puder ocupar o im\u00f3vel, em setembro de 2012. &#8220;Tenho esperan\u00e7as de   que algu\u00e9m tenha uma grande sacada e fa\u00e7a um estacionamento na frente&#8221;,   diz.<\/p>\n<p>De acordo com a legisla\u00e7\u00e3o municipal, tamb\u00e9m n\u00e3o h\u00e1 necessidade de   estudos de impacto de vizinhan\u00e7a para Habita\u00e7\u00f5es de Interesse Social   (HIS), como \u00e9 o caso do empreendimento da zona oeste.  A HIS e a  Habita\u00e7\u00e3o de Mercado Popular (HMP) s\u00e3o edifica\u00e7\u00f5es  encontradas nas Zonas  Especiais de Interesse Social (Zeis), onde h\u00e1  permiss\u00e3o para a exclus\u00e3o  das vagas de garagem. Adquirir um im\u00f3vel com  tais caracter\u00edsticas  depende de aprova\u00e7\u00f5es da renda do comprador.<\/p>\n<p>Para Maur\u00edlio Scacchetti, diretor comercial da HabitCasa, regi\u00f5es com   f\u00e1cil acesso permitem incorpora\u00e7\u00f5es de im\u00f3veis sem vaga: &#8220;Lan\u00e7amos   empreendimentos desses na Mooca, guia do bairro Br\u00e1s e <strong>guia da Barra Funda<\/strong>&#8220;. Em 2010, 10% dos  lan\u00e7amentos da empresa n\u00e3o tinham estacionamento.<\/p>\n<p>Com ou sem obriga\u00e7\u00f5es na legisla\u00e7\u00e3o, os impactos dos apartamentos sem   vaga podem ser grandes. Supondo que toda a extens\u00e3o das cinco ruas nas   imedia\u00e7\u00f5es da\u00a0 Barra Funda Park permitisse a parada de carros, haveria  1.686 metros pass\u00edveis de estacionamento.<\/p>\n<p>A medida, dividida pelo  comprimento m\u00e9dio de 4 metros por ve\u00edculo,  acomodaria 421 carros. S\u00f3 o  empreendimento tem 545 unidades sem vaga.  &#8220;Pode criar um impacto  extremamente negativo para a regi\u00e3o. J\u00e1 pensou  enfiar 500 carros na  \u00e1rea?&#8221;, diz o diretor da HabitCasa. A empresa \u00e9  vendedora do conjunto  habitacional, que foi aprovado pela Prefeitura de  acordo com as  exig\u00eancias legais.<\/p>\n<p><em>Fonte: O Estado de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Companhia de Engenharia de Tr\u00e1fego de S\u00e3o Paulo (CET) n\u00e3o realizou an\u00e1lise de impacto vi\u00e1rio em nenhum dos empreendimentos sem vagas lan\u00e7ados em 2010. A empresa cumpre a lei 10.506\/88, que determina estudos apenas para Polos Geradores Tr\u00e1fego. Para que isso ocorra, uma edifica\u00e7\u00e3o residencial deve ter pelo menos 500 vagas. Apesar da previs\u00e3o legal, especialistas preveem transtornos para a circula\u00e7\u00e3o em algumas regi\u00f5es. &#8220;Um tipo de impacto \u00e9 que o espa\u00e7o p\u00fablico seja tomado por ve\u00edculos particulares&#8221;, diz Luiz Guilherme Castro, professor do Mackenzie especializado em zoneamento urbano. O empreendimento Premmio Vila Nova, localizado na zona norte de <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-393","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=393"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/393\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}