{"id":475,"date":"2011-08-01T02:00:08","date_gmt":"2011-08-01T04:00:08","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=475"},"modified":"2019-04-29T17:21:00","modified_gmt":"2019-04-29T20:21:00","slug":"barra-funda-ganha-bairro-planejado","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/barra-funda-ganha-bairro-planejado\/","title":{"rendered":"Barra Funda ganha &#8216;bairro&#8217; planejado"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Um terreno de 250 mil m2, o equivalente a 25 quarteir\u00f5es, recebe investimentos para virar um &#8220;bairro&#8221; planejado no bairro Barra Funda (zona oeste da capital de SP).<\/p>\n<p>Nesta semana, as construtoras Tecnisa e PDG &#8211;que s\u00e3o as donas da \u00e1rea e respons\u00e1veis pela obra&#8211; come\u00e7am os trabalhos de infra-estrutura no local. As empresas n\u00e3o divulgaram o quanto ir\u00e3o investir, mas o valor de venda total est\u00e1 avaliado em R$ 4 bilh\u00f5es.<\/p>\n<p>O projeto prev\u00ea a constru\u00e7\u00e3o de cerca de 30 torres residenciais, com apartamentos de 90 m2 e 270 m2, duas torres comerciais e um centro para lojas de conveni\u00eancia, al\u00e9m de uma pra\u00e7a de 50 mil m2 que ser\u00e1 doada para a Prefeitura de S\u00e3o Paulo e aberta ao p\u00fablico.<\/p>\n<p><em>Fonte: Jornal Floripa<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Um terreno de 250 mil m2, o equivalente a 25 quarteir\u00f5es, recebe investimentos para virar um &#8220;bairro&#8221; planejado no bairro Barra Funda (zona oeste da capital de SP). Nesta semana, as construtoras Tecnisa e PDG &#8211;que s\u00e3o as donas da \u00e1rea e respons\u00e1veis pela obra&#8211; come\u00e7am os trabalhos de infra-estrutura no local. As empresas n\u00e3o divulgaram o quanto ir\u00e3o investir, mas o valor de venda total est\u00e1 avaliado em R$ 4 bilh\u00f5es. O projeto prev\u00ea a constru\u00e7\u00e3o de cerca de 30 torres residenciais, com apartamentos de 90 m2 e 270 m2, duas torres comerciais e um centro para lojas de <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-475","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=475"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/475\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}