{"id":528,"date":"2011-09-08T14:36:43","date_gmt":"2011-09-08T16:36:43","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=528"},"modified":"2019-04-29T17:20:18","modified_gmt":"2019-04-29T20:20:18","slug":"regiao-da-barra-funda-fica-sem-agua-sabesp-e-eletropaulo-divergem","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/regiao-da-barra-funda-fica-sem-agua-sabesp-e-eletropaulo-divergem\/","title":{"rendered":"Regi\u00e3o da Barra Funda fica sem \u00e1gua; Sabesp e Eletropaulo divergem"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>As regi\u00f5es da avenida Paulista, guia Jardins,  Perdizes e Vila Mariana ficaram  \u00e1gua nesta quinta-feira. A Sabesp  (Companhia de Saneamento B\u00e1sico do  Estado de S\u00e3o Paulo) e a AES  Eletropaulo divergem sobre a causa do  problema.<\/p>\n<p>A Sabesp diz que  faltou luz na esta\u00e7\u00e3o, por isso os sistemas pararam. A  Eletropaulo,  entretanto, afirma que n\u00e3o houve interrup\u00e7\u00e3o alguma. A  empresa admite  um problema na rede subterr\u00e2nea \u00e0s 5h de hoje. Mas o  sistema reserva  foi acionado de forma imediata, diz.<\/p>\n<p>A Eletropaulo diz, portanto, que n\u00e3o houve falta de energia na regi\u00e3o. Ela afirma que o problema foi dentro da esta\u00e7\u00e3o.<\/p>\n<p>J\u00e1  a concession\u00e1ria de \u00e1gua informou que apesar do problema, desde as   9h30, a esta\u00e7\u00e3o est\u00e1 trabalhando com um sistema auxiliar, o que deve   possibilitar a normaliza\u00e7\u00e3o do abastecimento no decorrer da tarde de   hoje.<\/p>\n<p>A recomenda\u00e7\u00e3o da Sabesp \u00e9 para que os moradores das \u00e1reas  afetadas  economizem a \u00e1gua armazenada nas caixas. Casos de emerg\u00eancia  podem ser  comunicados pelo telefone 195, que funciona 24 horas.<\/p>\n<p>Os bairros atingidos s\u00e3o: Aclima\u00e7\u00e3o, \u00c1gua Branca, Bairro Urbanizadora, Guia da Barra Funda, Bela Vista, Campos da Escol\u00e1stica, Cerqueira Cesar, Ch\u00e1cara  Itaim, Bairro da Consola\u00e7\u00e3o,  Higien\u00f3polis, Itaim Bibi, Jardim Am\u00e9rica, Jardim das  Bandeiras, Jardim  Europa, Jardim Paulistano, Liberdade, Mirand\u00f3polis,  Morro dos  Ingleses, Pacaembu, Para\u00edso, Parque Industrial, Perdizes,  Pinheiros,  Pompeia, Santa Cec\u00edlia, Sa\u00fade, Sumar\u00e9, Sumarezinho, Tomas  Edson, Vila  Clementino, Vila Deodoro, Vila dos Ferrovi\u00e1rios, Vila  Madalena, Vila  Mariana, Vila Nova Concei\u00e7\u00e3o, Vila Ol\u00edmpia e Vila  Primavera.<br \/>\n<em><br \/>\nFonte: Folha de S. Paulo<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>As regi\u00f5es da avenida Paulista, guia Jardins, Perdizes e Vila Mariana ficaram \u00e1gua nesta quinta-feira. A Sabesp (Companhia de Saneamento B\u00e1sico do Estado de S\u00e3o Paulo) e a AES Eletropaulo divergem sobre a causa do problema. A Sabesp diz que faltou luz na esta\u00e7\u00e3o, por isso os sistemas pararam. A Eletropaulo, entretanto, afirma que n\u00e3o houve interrup\u00e7\u00e3o alguma. A empresa admite um problema na rede subterr\u00e2nea \u00e0s 5h de hoje. Mas o sistema reserva foi acionado de forma imediata, diz. A Eletropaulo diz, portanto, que n\u00e3o houve falta de energia na regi\u00e3o. Ela afirma que o problema foi dentro da <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-528","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=528"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/528\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}