{"id":584,"date":"2011-11-04T13:59:29","date_gmt":"2011-11-04T15:59:29","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=584"},"modified":"2019-04-29T17:20:17","modified_gmt":"2019-04-29T20:20:17","slug":"barra-funda-ganhara-16-km-de-novas-vias","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/barra-funda-ganhara-16-km-de-novas-vias\/","title":{"rendered":"Barra Funda ganhar\u00e1 16 km de novas vias"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A Prefeitura de S\u00e3o Paulo pretende criar 16 km de novas ruas e avenidas  nos grandes terrenos desocupados do bairro da Barra Funda. A inten\u00e7\u00e3o do projeto,  que deve ser enviado \u00e0 C\u00e2mara Municipal at\u00e9 o fim do ano, \u00e9 povoar o  bairro para deix\u00e1-lo parecido com Perdizes, segundo a Folha de S. Paulo.<\/p>\n<p>Os grandes galp\u00f5es da regi\u00e3o ser\u00e3o substitu\u00eddos por pr\u00e9dios de  apartamentos e escrit\u00f3rios. O plano \u00e9 atrair cerca de 60 mil moradores  em at\u00e9 20 anos, fazendo a densidade populacional saltar dos atuais 25  para cerca de 170 habitantes a cada 10 mil m\u00b2.<\/p>\n<p><strong>Qualidades <\/strong><\/p>\n<p>Para a prefeitura, o bairro comporta tal adensamento por  possuir boa localiza\u00e7\u00e3o e infraestrutura adequada: \u00e9 pr\u00f3ximo do centro e  da marginal Tiet\u00ea, possui esta\u00e7\u00f5es de trem e metr\u00f4, corredores de  \u00f4nibus, uma rodovi\u00e1ria, dois shoppings e at\u00e9 um est\u00e1dio de futebol  (Palmeiras).<\/p>\n<p>O dinheiro que for arrecadado com os empreendimentos constru\u00eddos  acima do limite b\u00e1sico de \u00e1rea ser\u00e1 usado para a constru\u00e7\u00e3o das novas  vias e de obras contra enchentes. A ideia \u00e9 fixar 60% dos novos pr\u00e9dios  para fam\u00edlias com renda mensal de at\u00e9 16 sal\u00e1rios m\u00ednimos &#8211; moradores  que dever\u00e3o aproveitar melhor a infraestrutura de transportes p\u00fablicos  do bairro, segundo o secret\u00e1rio municipal de Desenvolvimento Urbano,  Miguel Bucalem.<\/p>\n<p><em>Fonte: Portal Destak<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de S\u00e3o Paulo pretende criar 16 km de novas ruas e avenidas nos grandes terrenos desocupados do bairro da Barra Funda. A inten\u00e7\u00e3o do projeto, que deve ser enviado \u00e0 C\u00e2mara Municipal at\u00e9 o fim do ano, \u00e9 povoar o bairro para deix\u00e1-lo parecido com Perdizes, segundo a Folha de S. Paulo. Os grandes galp\u00f5es da regi\u00e3o ser\u00e3o substitu\u00eddos por pr\u00e9dios de apartamentos e escrit\u00f3rios. O plano \u00e9 atrair cerca de 60 mil moradores em at\u00e9 20 anos, fazendo a densidade populacional saltar dos atuais 25 para cerca de 170 habitantes a cada 10 mil m\u00b2. Qualidades Para <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-584","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=584"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/584\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}