{"id":627,"date":"2011-12-26T00:01:03","date_gmt":"2011-12-26T02:01:03","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=627"},"modified":"2019-04-29T17:20:16","modified_gmt":"2019-04-29T20:20:16","slug":"barra-funda-circulacao-de-trens-da-cptm-esta-parada-ha-tres-dias-%e2%80%8e","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/barra-funda-circulacao-de-trens-da-cptm-esta-parada-ha-tres-dias-%e2%80%8e\/","title":{"rendered":"Barra Funda: Circula\u00e7\u00e3o de trens da CPTM est\u00e1 parada h\u00e1 tr\u00eas dias \u200e"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A circula\u00e7\u00e3o de trens da CPTM (CPTM Companhia Paulista de Trens Metropolitanos) continuava suspensa por volta das\u00a011h50 deste\u00a0domingo\u00a0(25).\u00a0 A interrup\u00e7\u00e3o foi feita, \u00e0s 11h15 desta quinta-feira (22), entre as esta\u00e7\u00f5es Guia Barra Funda (na zona oeste) e Luz (na regi\u00e3o central) da Linha7-Rubi; e entre as esta\u00e7\u00f5es Barra Funda e Julio Prestes, da Linha 8-Diamante por causa do inc\u00eandio na Favela do Moinho, em Campos El\u00edsios, regi\u00e3o central de S\u00e3o Paulo.<\/p>\n<p>De acordo com a assessoria da companhia, n\u00e3o h\u00e1 previs\u00e3o para a libera\u00e7\u00e3o da linha f\u00e9rrea, pois a CPTM aguarda o laudo da Defesa Civil sobre as condi\u00e7\u00f5es do pr\u00e9dio que foi queimado ao lado do local.<\/p>\n<p>Segundo o Corpo de Bombeiros, o trabalho de rescaldo (limpeza e contagem de preju\u00edzos) terminou nesta sexta-feira (23) por volta das 17h.<\/p>\n<p>Nesta sexta-feira (23), O Corpo de Bombeiros confirmou a segunda morte no inc\u00eandio. O corpo foi encontrado carbonizado no segundo andar do edif\u00edcio. Na quinta-feira (22), outro corpo foi encontrado carbonizado no primeiro pavimento.<\/p>\n<p>O inc\u00eandio come\u00e7ou por volta das 10h desta quinta-feira (22). No momento do inc\u00eandio, diversas pessoas estavam no andar superior do pr\u00e9dio abandonado e n\u00e3o conseguiram descer. Dois helic\u00f3pteros do grupamento a\u00e9reo da Pol\u00edcia Militar retiraram as pessoas que estavam por l\u00e1.<\/p>\n<p><em>Fonte: R7<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A circula\u00e7\u00e3o de trens da CPTM (CPTM Companhia Paulista de Trens Metropolitanos) continuava suspensa por volta das\u00a011h50 deste\u00a0domingo\u00a0(25).\u00a0 A interrup\u00e7\u00e3o foi feita, \u00e0s 11h15 desta quinta-feira (22), entre as esta\u00e7\u00f5es Guia Barra Funda (na zona oeste) e Luz (na regi\u00e3o central) da Linha7-Rubi; e entre as esta\u00e7\u00f5es Barra Funda e Julio Prestes, da Linha 8-Diamante por causa do inc\u00eandio na Favela do Moinho, em Campos El\u00edsios, regi\u00e3o central de S\u00e3o Paulo. De acordo com a assessoria da companhia, n\u00e3o h\u00e1 previs\u00e3o para a libera\u00e7\u00e3o da linha f\u00e9rrea, pois a CPTM aguarda o laudo da Defesa Civil sobre as condi\u00e7\u00f5es do <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-627","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=627"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/627\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}