{"id":661,"date":"2012-01-23T00:15:48","date_gmt":"2012-01-23T02:15:48","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=661"},"modified":"2019-04-29T17:20:16","modified_gmt":"2019-04-29T20:20:16","slug":"taxa-de-vacancia-na-barra-funda-fica-bem-proxma-de-zero-em-sp","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/taxa-de-vacancia-na-barra-funda-fica-bem-proxma-de-zero-em-sp\/","title":{"rendered":"Taxa de vac\u00e2ncia na Barra Funda fica bem pr\u00f3xma de zero em SP"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A demanda por \u00e1reas corporativas segue aquecida no munic\u00edpio de S\u00e3o Paulo. Conforme levantamento da Colliers International Brasil, referente ao 3\u00ba trimestre de 2011, a taxa de vac\u00e2ncia na cidade registrou queda nos \u00faltimos dois anos, alcan\u00e7ando 0,5%, mais uma vez, a menor verificada no mercado imobili\u00e1rio corporativo paulistano. No per\u00edodo de 12 meses, constatou-se queda de 2,3%. Contudo, na regi\u00e3o de Alphaville, a oferta \u00e9 vasta. A taxa de vac\u00e2ncia apresentada foi de 25,8%.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0 cidade de S\u00e3o Paulo, a regi\u00e3o da Berrini registrou queda de 2,5% de vac\u00e2ncia em rela\u00e7\u00e3o ao trimestre anterior, e as demais regi\u00f5es como Barra Funda, Ch\u00e1cara Santo Ant\u00f4nio, Faria Lima, Itaim, Marginal Pinheiros, Paulista (Jardins e Consola\u00e7\u00e3o), Roque Petroni e bairro Vila Ol\u00edmpia permanecem com as taxas bem pr\u00f3ximas de zero.<\/p>\n<p>O pre\u00e7o m\u00e9dio de loca\u00e7\u00e3o apurado no terceiro trimestre de 2011 foi R$ 110,50\/m\u00b2. O aumento acumulado dos pre\u00e7os pedidos em 2011 foi de 10%.\u00a0 As regi\u00f5es da Faria Lima e do Itaim permanecem com os maiores pre\u00e7os pedidos de loca\u00e7\u00e3o, R$ 200 e R$ 145, respectivamente, e, segundo o estudo, toda a sua macrorregi\u00e3o, que engloba Vila Ol\u00edmpia e Marginal Pinheiros (principalmente nas \u00e1reas pr\u00f3ximas \u00e0 Ponte Cidade Jardim), apresentar\u00e3o pre\u00e7os compat\u00edveis nos pr\u00f3ximos anos.<\/p>\n<p>Quando comparada a outros mercados da Am\u00e9rica Latina e do mundo, a taxa de vac\u00e2ncia paulistana aparece como a mais baixa, explicando os altos valores praticados na cidade. Em Toronto, a taxa de vac\u00e2ncia de escrit\u00f3rios de alto padr\u00e3o \u00e9 de 5,9%; seguida de Bogot\u00e1 (4,8%); Zurique (4,3%); Rio de Janeiro (4,6%); Hong Kong (3,7%); Lima (3,2%); entre outros.<\/p>\n<p>Tabela de pre\u00e7os m\u00e9dios por m\u00b2 classe A e A+<br \/>\nFaria Lima \u2013 R$ 175,5 \/ m\u00b2<br \/>\nItaim \u2013 R$ 146,00 \/ m\u00b2<br \/>\nMarginal Pinheiros \u2013 R$ 115,00 \/ m\u00b2<br \/>\nVila Ol\u00edmpia \u2013 R$ 113,00 \/ m\u00b2<br \/>\nPaulista \u2013 R$ 108,5 \/ m\u00b2<\/p>\n<p><em>Fonte: Metanalise<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A demanda por \u00e1reas corporativas segue aquecida no munic\u00edpio de S\u00e3o Paulo. Conforme levantamento da Colliers International Brasil, referente ao 3\u00ba trimestre de 2011, a taxa de vac\u00e2ncia na cidade registrou queda nos \u00faltimos dois anos, alcan\u00e7ando 0,5%, mais uma vez, a menor verificada no mercado imobili\u00e1rio corporativo paulistano. No per\u00edodo de 12 meses, constatou-se queda de 2,3%. Contudo, na regi\u00e3o de Alphaville, a oferta \u00e9 vasta. A taxa de vac\u00e2ncia apresentada foi de 25,8%. Em rela\u00e7\u00e3o \u00e0 cidade de S\u00e3o Paulo, a regi\u00e3o da Berrini registrou queda de 2,5% de vac\u00e2ncia em rela\u00e7\u00e3o ao trimestre anterior, e as demais <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-661","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=661"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/661\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}