{"id":713,"date":"2012-02-29T02:13:51","date_gmt":"2012-02-29T04:13:51","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=713"},"modified":"2019-04-29T17:20:15","modified_gmt":"2019-04-29T20:20:15","slug":"comecou-a-ser-julgado-na-barra-funda-padre-que-oferecia-cura-em-troca-de-sexo","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/comecou-a-ser-julgado-na-barra-funda-padre-que-oferecia-cura-em-troca-de-sexo\/","title":{"rendered":"Come\u00e7ou a ser julgado na Barra Funda padre que oferecia cura em troca de sexo"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Ex-fi\u00e9is e fam\u00edliares protestaram e pediram a condena\u00e7\u00e3o do l\u00edder e fundador Aldo Bertoni da Igreja Apost\u00f3lica, que foi criada para adorar ele mesmo. O caso come\u00e7ou a ser julgado na manh\u00e3 do dia 26\/02 no F\u00f3rum Criminal em guia da Barra Funda, na zona oeste de S\u00e3o Paulo.<\/p>\n<p>A den\u00fancia do Minist\u00e9rio P\u00fablico foi aceita pela Justi\u00e7a logo depois que o Domingo Espetacular exibiu uma reportagem exclusiva com depoimentos que acusam o suposto l\u00edder religioso de se aproveitar das fi\u00e9is. Aldo Bertoni responde por abuso sexual contra 15 mulheres. O processo corre em segredo de Justi\u00e7a.<\/p>\n<p>Dezenas de pessoas se reuniram, nesta segunda-feira 26\/02, em um protesto contra o pastor Aldo Bertoni, de 85 anos, suspeito de oferecer a cura para doen\u00e7as em troca de sexo numa seita que criou para adorar a si mesmo.<\/p>\n<p>Bertoni tem os passos acompanhados de perto pelo Minist\u00e9rio P\u00fablico desde 2009, quando a primeira v\u00edtima tomou coragem e procurou os promotores. Depois dela, dezenas de v\u00edtimas fizeram o mesmo.<\/p>\n<p>Na tarde do dia 26\/02 foram ouvidas as testemunhas de acusa\u00e7\u00e3o, uma nova data ser\u00e1 marcada para ouvir a defesa como tamb\u00e9m o pr\u00f3prio depoimento do acusado Aldo Bertoni.<\/p>\n<p><em>Fonte: O Di\u00e1rio<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Ex-fi\u00e9is e fam\u00edliares protestaram e pediram a condena\u00e7\u00e3o do l\u00edder e fundador Aldo Bertoni da Igreja Apost\u00f3lica, que foi criada para adorar ele mesmo. O caso come\u00e7ou a ser julgado na manh\u00e3 do dia 26\/02 no F\u00f3rum Criminal em guia da Barra Funda, na zona oeste de S\u00e3o Paulo. A den\u00fancia do Minist\u00e9rio P\u00fablico foi aceita pela Justi\u00e7a logo depois que o Domingo Espetacular exibiu uma reportagem exclusiva com depoimentos que acusam o suposto l\u00edder religioso de se aproveitar das fi\u00e9is. Aldo Bertoni responde por abuso sexual contra 15 mulheres. O processo corre em segredo de Justi\u00e7a. Dezenas de pessoas <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-713","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=713"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/713\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}