{"id":809,"date":"2012-05-21T10:29:47","date_gmt":"2012-05-21T12:29:47","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=809"},"modified":"2019-04-29T17:20:12","modified_gmt":"2019-04-29T20:20:12","slug":"caminhao-derruba-arvore-e-bloqueia-rua-na-barra-funda","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/caminhao-derruba-arvore-e-bloqueia-rua-na-barra-funda\/","title":{"rendered":"Caminh\u00e3o derruba \u00e1rvore e bloqueia rua na Barra Funda"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<div>\n<p>Uma \u00e1rvore de grande porte foi derrubada, por volta das 4 horas desta madrugada do \u00faltimo s\u00e1bado (19) por um caminh\u00e3o e bloqueia por completo a Rua Brigadeiro Galv\u00e3o na altura do n\u00ba 930, na Barra Funda, zona oeste de S\u00e3o Paulo.<\/p>\n<p>Ap\u00f3s esbarrar numa primeira \u00e1rvore, o ve\u00edculo de carga bateu numa segunda, que foi arrancada e atingiu, com a copa, um ve\u00edculo de passeio estacionado do outro lado da via. O carro estava vazio; n\u00e3o houve feridos. Ap\u00f3s causar o acidente, o caminhoneiro n\u00e3o permaneceu no local.<\/p>\n<p>A fia\u00e7\u00e3o da Eletropaulo tamb\u00e9m foi danificada com a queda da \u00e1rvore. Uma equipe dos bombeiros esperava, at\u00e9 as 5h15 desta manh\u00e3, pela chagada da Eletropaulo para que a energia na regi\u00e3o seja desligada e, assim, a \u00e1rvore possa ser cortada e retirada da rua.<\/p>\n<p><em>Fonte: Jornal de Floripa<\/em><\/p>\n<\/div>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Uma \u00e1rvore de grande porte foi derrubada, por volta das 4 horas desta madrugada do \u00faltimo s\u00e1bado (19) por um caminh\u00e3o e bloqueia por completo a Rua Brigadeiro Galv\u00e3o na altura do n\u00ba 930, na Barra Funda, zona oeste de S\u00e3o Paulo. Ap\u00f3s esbarrar numa primeira \u00e1rvore, o ve\u00edculo de carga bateu numa segunda, que foi arrancada e atingiu, com a copa, um ve\u00edculo de passeio estacionado do outro lado da via. O carro estava vazio; n\u00e3o houve feridos. Ap\u00f3s causar o acidente, o caminhoneiro n\u00e3o permaneceu no local. A fia\u00e7\u00e3o da Eletropaulo tamb\u00e9m foi danificada com a queda da <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-809","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=809"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/809\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}