{"id":86,"date":"2010-12-13T11:36:12","date_gmt":"2010-12-13T13:36:12","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=86"},"modified":"2019-04-29T17:21:26","modified_gmt":"2019-04-29T20:21:26","slug":"estacao-barra-funda-foi-fechada-apos-falha-no-metro-sp","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/estacao-barra-funda-foi-fechada-apos-falha-no-metro-sp\/","title":{"rendered":"Esta\u00e7\u00e3o Barra Funda foi fechada ap\u00f3s falha no Metr\u00f4-SP"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<div id=\"materia-letra\">\n<div>\n<p>A esta\u00e7\u00e3o Barra Funda, da Companhia do  Metropolitano de S\u00e3o Paulo (Metr\u00f4), foi fechada para a entrada de  passageiros. O motivo do bloqueio \u00e9foi uma falha em equipamento da Linha 3 &#8211;  Vermelha (Palmeiras\/Barra Funda &#8211; Corinthians\/Itaquera), ocorrida \u00e0s  16h50 da tarde de sexta-feira, que causou excesso de pessoas na esta\u00e7\u00e3o.<\/p>\n<p>As demais esta\u00e7\u00f5es da linha Vermelha foram abertas, por\u00e9m com  restri\u00e7\u00e3o para a entrada de usu\u00e1rios. Os trens das linhas 3 &#8211; Vermelha, 1  &#8211; Azul e 2 &#8211; Verde operaram com velocidade reduzida e maior intervalo  entre as composi\u00e7\u00f5es.<\/p>\n<p><em>Fonte: G1<\/em><\/p>\n<\/div>\n<\/div>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A esta\u00e7\u00e3o Barra Funda, da Companhia do Metropolitano de S\u00e3o Paulo (Metr\u00f4), foi fechada para a entrada de passageiros. O motivo do bloqueio \u00e9foi uma falha em equipamento da Linha 3 &#8211; Vermelha (Palmeiras\/Barra Funda &#8211; Corinthians\/Itaquera), ocorrida \u00e0s 16h50 da tarde de sexta-feira, que causou excesso de pessoas na esta\u00e7\u00e3o. As demais esta\u00e7\u00f5es da linha Vermelha foram abertas, por\u00e9m com restri\u00e7\u00e3o para a entrada de usu\u00e1rios. Os trens das linhas 3 &#8211; Vermelha, 1 &#8211; Azul e 2 &#8211; Verde operaram com velocidade reduzida e maior intervalo entre as composi\u00e7\u00f5es. Fonte: G1<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-86","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}