{"id":869,"date":"2012-07-11T18:40:25","date_gmt":"2012-07-11T20:40:25","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=869"},"modified":"2019-04-29T17:19:55","modified_gmt":"2019-04-29T20:19:55","slug":"confronto-entre-torcidas-de-corinthians-e-palmeiras-pode-acontecer-na-barra-funda-evite","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/confronto-entre-torcidas-de-corinthians-e-palmeiras-pode-acontecer-na-barra-funda-evite\/","title":{"rendered":"Confronto entre torcidas de Corinthians e Palmeiras pode acontecer na Barra Funda; evite"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Hoje a partir das 19:30 o Corinthians, time que conquistou recentemente a Libertadores 2012, enfrenta o time do Botafogo pelo campeonato Brasileiro no Est\u00e1dio do Pacaembu.<\/p>\n<p>Do outro lado, com a decis\u00e3o da Copa do Brasil disputada em Curitiba, longe de S\u00e3o Paulo, a diretoria do <a title=\"Sociedade Esportiva Palmeiras\" href=\"http:\/\/www.encontrabarrafunda.com.br\/barra-funda\/sociedade-esportiva-palmeiras.shtml\" target=\"_blank\">Palmeiras<\/a> preparou e alugou dois pontos de concentra\u00e7\u00e3o para que os torcedores sem ingresso possam assistir \u00e0 final, contra o Coritiba, \u00e0s 21h50 desta quarta-feira. Com ingressos a R$ 50, o clube disponibilizar\u00e1 um tel\u00e3o de LED para 8 mil torcedores na Arena Expo Barra Funda, na Zona Oeste de S\u00e3o Paulo \u2013 torcedores com a camisa oficial do clube pagam meia entrada, a R$ 25.<\/p>\n<p>Muitos torcedores devem comparecer ao evento utilizando a Esta\u00e7\u00e3o Palmeiras Barra Funda, e \u00e9 ai que podem come\u00e7ar os problemas. A torcida do Corinthians utiliza a mesma linha para chegar ao Est\u00e1dio do Pacaembu. Os torcedores que utilizam o metr\u00f4 desembarcam nas esta\u00e7\u00e3o Cl\u00ednicas (Linha verde) e na esta\u00e7\u00e3o vizinha, a esta\u00e7\u00e3o Marechal Deodoro, j\u00e1 os torcedores que vem de Osasco, Francisco Morato e Itapevi costumam descer na Esta\u00e7\u00e3o de Metr\u00f4 Palmeiras Barra Funda.<\/p>\n<p>Preocupada com\u00a0 um poss\u00edvel encontro, a principal torcida do Corinthians soltou uma nota pedindo aos seus torcedores que tomem cuidado e sigam em paz para o est\u00e1dio.<\/p>\n<p>Confira a nota na integra:<\/p>\n<p><em>&#8220;Comunicado para o Jogo de hoje Corinthians x Botafogo<\/em><\/p>\n<p><em>Aten\u00e7\u00e3o Na\u00e7\u00e3o Corinthiana<\/em><\/p>\n<p><em>Hoje nosso jogo acontece no Pacaembu \u00e0s 19h30, e alertamos a todos os Corinthianos que no mesmo hor\u00e1rio, ter\u00e1 tel\u00e3o no Memorial da Am\u00e9rica (Barra Funda) para o jogo do Palmeiras. Fiquem atentos para que todos cheguem com seguran\u00e7a ao est\u00e1dio e evitem passar por essa regi\u00e3o. Para os que forem passar,cuidado com camisas, e qualquer tipo de roupas e bandeiras do Corinthians. Vamos manter a paz e irmos todos para o jogo sem criar nenhum tipo de problema.&#8221;<\/em><\/p>\n<p><em>\u00a0*Colaboraram Tallyta Vieira e Leonardo Vieira<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Hoje a partir das 19:30 o Corinthians, time que conquistou recentemente a Libertadores 2012, enfrenta o time do Botafogo pelo campeonato Brasileiro no Est\u00e1dio do Pacaembu. Do outro lado, com a decis\u00e3o da Copa do Brasil disputada em Curitiba, longe de S\u00e3o Paulo, a diretoria do Palmeiras preparou e alugou dois pontos de concentra\u00e7\u00e3o para que os torcedores sem ingresso possam assistir \u00e0 final, contra o Coritiba, \u00e0s 21h50 desta quarta-feira. Com ingressos a R$ 50, o clube disponibilizar\u00e1 um tel\u00e3o de LED para 8 mil torcedores na Arena Expo Barra Funda, na Zona Oeste de S\u00e3o Paulo \u2013 torcedores <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-869","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=869"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/869\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}