{"id":953,"date":"2012-09-13T12:03:46","date_gmt":"2012-09-13T14:03:46","guid":{"rendered":"http:\/\/www.encontrabarrafunda.com.br\/noticias\/?p=953"},"modified":"2019-04-29T17:19:54","modified_gmt":"2019-04-29T20:19:54","slug":"barra-funda-prefeitura-vistoria-obras-das-fabricas-de-samba","status":"publish","type":"post","link":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/barra-funda-prefeitura-vistoria-obras-das-fabricas-de-samba\/","title":{"rendered":"Barra Funda: Prefeitura vistoria obras das F\u00e1bricas de Samba"},"content":{"rendered":"<div class=\"7c2b2ddf12efdbbbe85a507d14b9627a\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Autoridades municipais e representantes de escolas de samba vistoriaram na manh\u00e3 desta quarta-feira (12) as obras das \u201cF\u00e1bricas de Samba\u201d, localizada na Avenida Abra\u00e3o Ribeiro, n\u00ba 497, Barra Funda \u2013 Zona Norte de SP, pr\u00f3ximo ao Samb\u00f3dromo. O complexo, que tem previs\u00e3o de entrega para 2013, concentrar\u00e1 toda a produ\u00e7\u00e3o carnavalesca em s\u00f3 um ponto, beneficiando o tr\u00e2nsito no per\u00edodo do carnaval, al\u00e9m de contribuir para a mem\u00f3ria da festa em S\u00e3o Paulo.<\/p>\n<p>As F\u00e1bricas de Samba s\u00e3o erguidas em um terreno p\u00fablico de 77 mil m\u00b2 na Marginal do Tiet\u00ea, distante apenas um quil\u00f4metro do samb\u00f3dromo. O projeto compreende 14 barrac\u00f5es (com 4.200 m\u00b2 cada), al\u00e9m do barrac\u00e3o-escola e sede administrativa. Haver\u00e1 ainda uma arena central para eventos e pequenas exposi\u00e7\u00f5es, estacionamento e vias internas de circula\u00e7\u00e3o de ve\u00edculos leves e pesados, de forma segura e sem interfer\u00eancia com as \u00e1reas.<\/p>\n<p>O local escolhido possui em seu entorno uma s\u00e9rie de servi\u00e7os j\u00e1 consolidados, como eficiente sistema de transportes &#8211; interligado pelo metr\u00f4, CPTM, al\u00e9m de tr\u00eas corredores de \u00f4nibus \u2013 hospitais, creches e escolas de ensino m\u00e9dio e profissionalizante.<\/p>\n<p>As obras das F\u00e1bricas de Samba tiveram in\u00edcio em fevereiro de 2012, com cronograma de 18 meses, representando investimentos de R$ 124 milh\u00f5es. At\u00e9 agora, j\u00e1 foram executados trabalhos de limpeza do terreno, terraplanagem e funda\u00e7\u00e3o dos Blocos A, B e C, al\u00e9m da montagem parcial de estrutura pr\u00e9-moldada dos Blocos A e C.<\/p>\n<p>Hoje os barrac\u00f5es est\u00e3o espalhados por v\u00e1rios pontos da cidade, fazendo com que o transporte dos carros aleg\u00f3ricos, fantasias e adere\u00e7os at\u00e9 o Samb\u00f3dromo seja uma das opera\u00e7\u00f5es mais delicadas de todo o Carnaval. Ao propor as \u201cF\u00e1bricas de Samba\u201d, a Prefeitura busca garantir \u00e0s escolas de samba melhores condi\u00e7\u00f5es de trabalho, que ir\u00e3o refletir imediatamente na qualidade dos desfiles carnavalescos. Haver\u00e1 tamb\u00e9m um impacto positivo na gera\u00e7\u00e3o e qualifica\u00e7\u00e3o da m\u00e3o-de-obra utilizada para a produ\u00e7\u00e3o do evento, a cria\u00e7\u00e3o de um novo ponto tur\u00edstico e a implanta\u00e7\u00e3o de diversos projetos de cunho s\u00f3cio-educativos e de inclus\u00e3o.<br \/>\n<strong><br \/>\nComo funcionar\u00e1<\/strong><\/p>\n<p>Nas F\u00e1bricas, cada escola de samba do Grupo Especial ter\u00e1 um barrac\u00e3o que atenda \u00e0s suas necessidades de produ\u00e7\u00e3o de carros aleg\u00f3ricos \u2013 em todas as suas fases \u2013 al\u00e9m de fantasias e adere\u00e7os. Em cada um dos barrac\u00f5es trabalhar\u00e3o, em hor\u00e1rio comercial, em m\u00e9dia 120 homens e mulheres, com o manuseio de produtos qu\u00edmicos, como tintas, e materiais diversos, como isopor, tecido, pl\u00e1stico, vidro, madeira, entre outros.<\/p>\n<p>Os barrac\u00f5es foram projetados e ser\u00e3o constru\u00eddos de acordo com as peculiaridades das atividades que ali ser\u00e3o desenvolvidas, considerando as necessidades de espa\u00e7os livres, de circula\u00e7\u00e3o e das fases de produ\u00e7\u00e3o. O empreendimento ainda ter\u00e1 uma estrutura de recep\u00e7\u00e3o tur\u00edstica adequada ao porte e \u00e0 import\u00e2ncia do tema, se transformando em um novo polo tur\u00edstico para a cidade, proporcionando acesso a toda riqueza cultural envolvida no Carnaval.<\/p>\n<p>Com exce\u00e7\u00e3o dos per\u00edodos mais cr\u00edticos da elabora\u00e7\u00e3o dos carros aleg\u00f3ricos (que exigem sigilo), nos demais meses do ano os barrac\u00f5es estar\u00e3o abertos, e os turistas ser\u00e3o recepcionados pelos profissionais que trabalhar\u00e3o no local. Ao chegar, o visitante tamb\u00e9m poder\u00e1 manusear instrumentos e ter breves aulas de ritmo, al\u00e9m de pain\u00e9is e proje\u00e7\u00f5es que simular\u00e3o a passarela do samba.<\/p>\n<p>A preserva\u00e7\u00e3o do rico acervo cultural do samba da cidade de S\u00e3o Paulo tamb\u00e9m ser\u00e1 contemplada por meio da abertura do Memorial do Samba, local adequado \u00e0 import\u00e2ncia do tema, que reunir\u00e1 acervos fotogr\u00e1ficos e exposi\u00e7\u00f5es, documentos, grava\u00e7\u00f5es antigas, document\u00e1rios e filmes, podendo ser consultado por visitantes ou pesquisadores.<\/p>\n<p><em>Fonte: Prefeitura de S. Paulo\u00a0<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Autoridades municipais e representantes de escolas de samba vistoriaram na manh\u00e3 desta quarta-feira (12) as obras das \u201cF\u00e1bricas de Samba\u201d, localizada na Avenida Abra\u00e3o Ribeiro, n\u00ba 497, Barra Funda \u2013 Zona Norte de SP, pr\u00f3ximo ao Samb\u00f3dromo. O complexo, que tem previs\u00e3o de entrega para 2013, concentrar\u00e1 toda a produ\u00e7\u00e3o carnavalesca em s\u00f3 um ponto, beneficiando o tr\u00e2nsito no per\u00edodo do carnaval, al\u00e9m de contribuir para a mem\u00f3ria da festa em S\u00e3o Paulo. As F\u00e1bricas de Samba s\u00e3o erguidas em um terreno p\u00fablico de 77 mil m\u00b2 na Marginal do Tiet\u00ea, distante apenas um quil\u00f4metro do samb\u00f3dromo. O projeto compreende <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-953","post","type-post","status-publish","format-standard","hentry","category-noticias-na-barra-funda"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=953"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/posts\/953\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabarrafunda.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}